{"id":36,"count":2,"description":"","link":"https:\/\/itpatagonia.live\/es\/blog\/tag\/formacion","name":"Formaci\u00f3n","slug":"formacion","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Formaci\u00f3n archivos - IT Patagonia<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Formaci\u00f3n archivos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itpatagonia.live\/es\/blog\/tag\/formacion\/\" \/>\n<meta property=\"og:site_name\" content=\"IT Patagonia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/blog\\\/tag\\\/formacion\",\"url\":\"https:\\\/\\\/itpatagonia.live\\\/blog\\\/tag\\\/formacion\",\"name\":\"Formaci\u00f3n archivos - IT Patagonia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/blog\\\/tag\\\/formacion#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/blog\\\/tag\\\/formacion#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/itpatagonia.live\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Formaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/#website\",\"url\":\"https:\\\/\\\/itpatagonia.live\\\/\",\"name\":\"IT Patagonia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/itpatagonia.live\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/#organization\",\"name\":\"IT Patagonia\",\"url\":\"https:\\\/\\\/itpatagonia.live\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/itpatagonia.live\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/IT-Patagonia-logo-web.png\",\"contentUrl\":\"https:\\\/\\\/itpatagonia.live\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/IT-Patagonia-logo-web.png\",\"width\":350,\"height\":100,\"caption\":\"IT Patagonia\"},\"image\":{\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/itpatagonia\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Formaci\u00f3n archivos - IT Patagonia","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Formaci\u00f3n archivos","og_url":"https:\/\/itpatagonia.live\/es\/blog\/tag\/formacion\/","og_site_name":"IT Patagonia","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/itpatagonia.live\/blog\/tag\/formacion","url":"https:\/\/itpatagonia.live\/blog\/tag\/formacion","name":"Formaci\u00f3n archivos - IT Patagonia","isPartOf":{"@id":"https:\/\/itpatagonia.live\/#website"},"breadcrumb":{"@id":"https:\/\/itpatagonia.live\/blog\/tag\/formacion#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/itpatagonia.live\/blog\/tag\/formacion#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/itpatagonia.live\/"},{"@type":"ListItem","position":2,"name":"Formaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/itpatagonia.live\/#website","url":"https:\/\/itpatagonia.live\/","name":"IT Patagonia","description":"","publisher":{"@id":"https:\/\/itpatagonia.live\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itpatagonia.live\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/itpatagonia.live\/#organization","name":"IT Patagonia","url":"https:\/\/itpatagonia.live\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/itpatagonia.live\/#\/schema\/logo\/image\/","url":"https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/11\/IT-Patagonia-logo-web.png","contentUrl":"https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/11\/IT-Patagonia-logo-web.png","width":350,"height":100,"caption":"IT Patagonia"},"image":{"@id":"https:\/\/itpatagonia.live\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/itpatagonia\/"]}]}},"_links":{"self":[{"href":"https:\/\/itpatagonia.live\/es\/wp-json\/wp\/v2\/tags\/36","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itpatagonia.live\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/itpatagonia.live\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/itpatagonia.live\/es\/wp-json\/wp\/v2\/posts?tags=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}