{"id":9001,"date":"2023-12-19T20:47:42","date_gmt":"2023-12-19T19:47:42","guid":{"rendered":"https:\/\/itpatagonia.live\/?p=9001"},"modified":"2026-04-20T15:27:01","modified_gmt":"2026-04-20T13:27:01","slug":"cobol-por-que-sigue-vigente","status":"publish","type":"post","link":"https:\/\/itpatagonia.live\/es\/blog\/cobol-por-que-sigue-vigente","title":{"rendered":"COBOL, el lenguaje &#8220;cancelado&#8221; que sigue tan vigente como el primer d\u00eda"},"content":{"rendered":"<p class=\"wp-block-paragraph\">El lenguaje COBOL no aparece nunca en los primeros puestos de los <a href=\"https:\/\/www.tiobe.com\/tiobe-index\/\" target=\"_blank\" rel=\"noreferrer noopener\">principales rankings de programaci\u00f3n<\/a>. A la vista de las generaciones de desarrolladores j\u00f3venes, est\u00e1 \u201cpasado de moda\u201d. Hay poca oferta acad\u00e9mica para aprenderlo: menos del 30% de las universidades a nivel mundial lo incluye en su curr\u00edcula.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, \u00bfes tan as\u00ed? \u00bfEl hecho de que tenga m\u00e1s de 60 a\u00f1os de vida hace a COBOL un lenguaje poco eficiente y no adaptable a las nuevas tecnolog\u00edas? \u00bfLe queda a COBOL poco tiempo, como ya varias veces se predijo sin \u00e9xito?\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestra experiencia liderando proyectos de modernizaci\u00f3n COBOL indica que no. <strong>COBOL sigue siendo imprescindible<\/strong> en las estructuras de sistemas de las industrias que procesan grandes vol\u00famenes de datos. Y a\u00fan no se ha creado un lenguaje que supere sus principales diferenciales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este art\u00edculo analizamos las principales razones de la vigencia de COBOL y las oportunidades de crecimiento profesional que surgen a partir de la formaci\u00f3n del talento joven, para ellos y para las empresas empleadoras.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 es COBOL y para qu\u00e9 sirve?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">COBOL es el acr\u00f3nimo de Common Business Oriented Language (Lenguaje com\u00fan orientado a negocios).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como su nombre lo indica, es un <strong>lenguaje de programaci\u00f3n orientado a los negocios y la administraci\u00f3n<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Naci\u00f3 en 1959 en Estados Unidos, de manos de la Conference on Data Systems Languages (CODASYL), con <a href=\"https:\/\/www.historyofinformation.com\/detail.php?id=754\" target=\"_blank\" rel=\"noreferrer noopener\">inspiraci\u00f3n en el compilador Flow-Matic<\/a> de Grace Hopper.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los a\u00f1os 50, el desarrollo de sistemas requer\u00eda un alto nivel de conocimiento y especializaci\u00f3n. Se usaban lenguajes de bajo nivel y lenguaje ensamblador, que requer\u00edan mucho entrenamiento y trabajo meticuloso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proyecto de creaci\u00f3n de COBOL tuvo como objetivo resolver esa imperiosa necesidad del sector: <a href=\"https:\/\/www.silicon.es\/no-se-que-lenguajes-habra-en-el-futuro-pero-seguro-que-cobol-estara-todavia-alli-2225103#:~:text=La%20importancia%20del%20COBOL%20se,se%20adaptan%20mejor%20al%20medio.\" target=\"_blank\" rel=\"noreferrer noopener\">normalizar los lenguajes que utilizaban los equipos inform\u00e1ticos<\/a> y \u201cpopularizar\u201d la programaci\u00f3n.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y lo hizo de forma efectiva. La integraci\u00f3n del lenguaje COBOL permite desplegar las aplicaciones en plataformas como .NET, Java Virtual Machine (JVM) y entornos cloud, <strong>sin que sea necesario modificar una sola l\u00ednea del c\u00f3digo<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"870\" height=\"300\" src=\"https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/12\/Cobol_Img-interna_3-1.jpg\" alt=\"\" class=\"wp-image-9489\" srcset=\"https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/12\/Cobol_Img-interna_3-1.jpg 870w, https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/12\/Cobol_Img-interna_3-1-300x103.jpg 300w, https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/12\/Cobol_Img-interna_3-1-768x265.jpg 768w, https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/12\/Cobol_Img-interna_3-1-720x248.jpg 720w\" sizes=\"(max-width: 870px) 100vw, 870px\" \/><figcaption class=\"wp-element-caption\">COBOL populariz\u00f3 la programaci\u00f3n y ayud\u00f3 a la industria a expandirse.\u00a0<\/figcaption><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Estas caracter\u00edsticas distintivas hicieron que COBOL tuviera un impacto inmediato en la computaci\u00f3n comercial y administrativa y sea, hasta el d\u00eda de hoy, <strong>un lenguaje de programaci\u00f3n muy popular en el mundo de los negocios<\/strong>.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se lo utiliza en una amplia gama de aplicaciones, de gesti\u00f3n de bases de datos, de procesamiento de transacciones y de planificaci\u00f3n (ERP), por tres caracter\u00edsticas distintivas: <strong>robustez, fiabilidad y portabilidad<\/strong> de su l\u00f3gica de negocios.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos atributos son tambi\u00e9n los que lo convirtieron en la columna vertebral del sistema financiero, como lenguaje ideal para desarrollar aplicaciones que requieren un alto rendimiento y bajo mantenimiento.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 es lo que hizo a este lenguaje tan especial?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El hecho de que los programas escritos en COBOL puedan ejecutarse en una amplia gama de plataformas es un diferencial importante. Adem\u00e1s, es el lenguaje elegido para escribir las aplicaciones y programas cr\u00edticos de las organizaciones, <strong>por la confianza, solidez y seguridad que provee.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.linkedin.com\/in\/leonardo-zrycki\/\" target=\"_blank\" rel=\"noreferrer noopener\">Leonardo Zrycki<\/a>, IBM Champion 2023 zSystem y capacitador COBOL en IT Patagonia, suma otro diferencial: su <strong>facilidad en la capacitaci\u00f3n y el entendimiento de los programas<\/strong>. \u201cAl ser un lenguaje \u2018English like\u2019 es f\u00e1cilmente comprensible. Adem\u00e1s, es compilable, por lo que sus ejecutables tienen una alta velocidad de procesamiento\u201d, explica.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta cualidad fue definida como objetivo desde el nacimiento de COBOL: crear un lenguaje que permitiera que personas sin conocimientos de inform\u00e1tica pudieran comunicarse con m\u00e1s eficacia con las computadoras, <strong>para satisfacer la creciente necesidad de una tecnolog\u00eda abierta<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 convirti\u00f3 a COBOL en la columna vertebral del sistema financiero? Precisamente el hecho de ser un <strong>programa de f\u00e1cil entendimiento y comprensi\u00f3n, y su solidez y seguridad<\/strong>, factores que hicieron que industrias clave -como la financiera-, lo adoptaran y prefirieran.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre sus caracter\u00edsticas principales se destacan:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cEnglish like\u201d, f\u00e1cil de entender y escribir en una sintaxis similar a la del idioma ingl\u00e9s<\/li>\n\n\n\n<li>Simple de documentar<\/li>\n\n\n\n<li>Especial para procesar grandes vol\u00famenes de datos, centenares de miles de registros<\/li>\n\n\n\n<li>Al ser un lenguaje compilado, tiene alta velocidad de procesamiento<\/li>\n\n\n\n<li>Programaci\u00f3n y tipos de datos estructurados<\/li>\n\n\n\n<li>Conexi\u00f3n con archivos de todo tipo y bases de datos relacionales<\/li>\n\n\n\n<li>Admite SQL embebido<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">El hecho de que ning\u00fan otro lenguaje haya propuesto los mismos diferenciales en los 60 a\u00f1os que pasaron desde su creaci\u00f3n y el alto costo de migrar han afianzado la vigencia de COBOL.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfPor qu\u00e9 se sigue usando COBOL?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A lo largo de los a\u00f1os de existencia de COBOL han surgido nuevos lenguajes de programaci\u00f3n, que se ganaron el coraz\u00f3n de las nuevas generaciones de desarrolladores.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, COBOL se mantiene activo, desafiando a la escasez de profesionales, que en la actualidad <strong>superan en promedio los 55 a\u00f1os de edad en el mundo<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su vigencia se justifica en que es la base de una gran cantidad de sistemas a\u00fan en uso, en las principales industrias del mundo. Debido al alto costo y el riesgo que tiene reescribir o migrar estos sistemas a lenguajes m\u00e1s modernos, <strong>las organizaciones siguen apostando a COBOL<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan Zrycki, su actualidad se explica por el <strong>maridaje perfecto entre su evoluci\u00f3n y la de los sistemas de IBM<\/strong> -tanto ISeries como zSeries-, que han optimizado su eficiencia y permiten una alta transaccionalidad.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta transformaci\u00f3n sincronizada hizo que las grandes compa\u00f1\u00edas del mundo, que sustentan sus sistemas core en mainframes, lo sigan utilizando, porque COBOL demostr\u00f3 a lo largo de los a\u00f1os <a href=\"https:\/\/www.cronista.com\/infotechnology\/finanzas-digitales\/podria-estar-jubilado-pero-decidio-ensenar-cobol-a-los-jovenes-el-lenguaje-que-usan-los-bancos\/\" target=\"_blank\" rel=\"noreferrer noopener\">ser muy estable en todo lo que tiene que ver con l\u00f3gica de negocio<\/a>.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, <strong>se fue modernizando a medida que la tecnolog\u00eda evoluciona y que los usuarios lo demandan<\/strong>. El lenguaje se transform\u00f3 con el paso del tiempo, sumando programaci\u00f3n estructurada, la posibilidad de anidar programas y admisi\u00f3n de recursividad. Y, desde 2002, COBOL admite la programaci\u00f3n orientada a objetos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"870\" height=\"300\" src=\"https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/12\/Cobol_Img-interna_1-1-1.jpg\" alt=\"\" class=\"wp-image-9484\" srcset=\"https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/12\/Cobol_Img-interna_1-1-1.jpg 870w, https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/12\/Cobol_Img-interna_1-1-1-300x103.jpg 300w, https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/12\/Cobol_Img-interna_1-1-1-768x265.jpg 768w, https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/12\/Cobol_Img-interna_1-1-1-720x248.jpg 720w\" sizes=\"(max-width: 870px) 100vw, 870px\" \/><figcaption class=\"wp-element-caption\">Como lo pronostic\u00f3 Bill Gates, a 60 a\u00f1os de su nacimiento COBOL se mantiene activo y no piensa retirarse.<\/figcaption><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 se puede programar en con el lenguaje &#8220;dinosaurio&#8221;?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La programaci\u00f3n COBOL -particularmente en los mainframe IBM zSystem-, resuelve la l\u00f3gica de negocio, tanto en procesos online como batch, y es utilizado en el desarrollo de una amplia gama de aplicaciones:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Financieras<\/strong>. Es el lenguaje m\u00e1s utilizado en el sector financiero, para desarrollar sistemas de procesamiento de pagos, gesti\u00f3n de inversiones y cumplimiento normativo.<\/li>\n\n\n\n<li><strong>De gesti\u00f3n<\/strong>. Se utiliza para desarrollar sistemas para la gesti\u00f3n de inventarios, planificaci\u00f3n de recursos empresariales (ERP) y gesti\u00f3n de relaciones con los clientes (CRM).<\/li>\n\n\n\n<li><strong>De gobierno<\/strong>. Se usa para desarrollar sistemas para la administraci\u00f3n de impuestos, la gesti\u00f3n de beneficios y la seguridad nacional.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">COBOL en el mundo empresarial<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Como anticipamos, en el desarrollo de aplicaciones modernas, COBOL no es un lenguaje de programaci\u00f3n muy popular. Pero <strong>sigue siendo muy utilizado para mantener y modernizar las existentes<\/strong>.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan <a href=\"https:\/\/fingfx.thomsonreuters.com\/gfx\/rngs\/USA-BANKS-COBOL\/010040KH18J\/index.html\" target=\"_blank\" rel=\"noreferrer noopener\">estad\u00edsticas del sector<\/a>, el <strong>92% de las principales entidades financieras del mundo lo usan,<\/strong> y por COBOL pasa el 95% de las operaciones realizadas en cajeros autom\u00e1ticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta masividad y la gran penetraci\u00f3n en las industrias m\u00e1s importantes explica en parte la vigencia de COBOL que mencionamos en el t\u00edtulo.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, su actualidad est\u00e1 dada por la constante modernizaci\u00f3n de este lenguaje.\u00a0Por ejemplo, en las \u00faltimas versiones de COBOL para zSystem, <strong>la interoperabilidad entre este lenguaje y Java fue mejorada<\/strong> y permite llamar desde un COBOL a uno Java y viceversa.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"870\" height=\"300\" src=\"https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/12\/Cobol_Img-interna_2.jpg\" alt=\"Las principales industrias del mundo utilizan Cobol.\" class=\"wp-image-9486\" srcset=\"https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/12\/Cobol_Img-interna_2.jpg 870w, https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/12\/Cobol_Img-interna_2-300x103.jpg 300w, https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/12\/Cobol_Img-interna_2-768x265.jpg 768w, https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/12\/Cobol_Img-interna_2-720x248.jpg 720w\" sizes=\"(max-width: 870px) 100vw, 870px\" \/><figcaption class=\"wp-element-caption\">Si bien no es un lenguaje de programaci\u00f3n muy popular, COBOL sigue siendo muy utilizado para mantener y modernizar las existentes.\u00a0<\/figcaption><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Proyecci\u00f3n profesional para desarrolladores<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La transformaci\u00f3n digital y la aparici\u00f3n de nuevos lenguajes y entornos de programaci\u00f3n provoc\u00f3 el descenso de la oferta de desarrolladores en lenguaje COBOL.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como consecuencia, <strong>el mercado mundial lucha con la escasez de perfiles senior<\/strong>. Por ejemplo, en Argentina se estima que son m\u00e1s de <a href=\"https:\/\/www.forbesargentina.com\/negocios\/lanzan-bolsa-empleo-it-conectar-jovenes-talentos-mas-1800-empresas-sector-n36998\" target=\"_blank\" rel=\"noreferrer noopener\">15 mil los puestos de trabajo IT sin cubrir<\/a>, cifra que crece a\u00f1o a a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parad\u00f3jicamente, las carreras de tecnolog\u00eda tienen baja matriculaci\u00f3n y, como consecuencia, aumenta el desempleo en este rubro. Adem\u00e1s, m\u00e1s del 70% de las carreras tecnol\u00f3gicas excluye a COBOL de su plan de estudios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este contexto abre una <strong>gran oportunidad de desarrollo profesional en el campo de la programaci\u00f3n en COBOL<\/strong>. Y la casi plena seguridad de tener un puesto de trabajo asegurado si se es desarrollador senior o semi senior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Las organizaciones necesitan cubrir los puestos que dejan los trabajadores que llegan a su retiro profesional<\/strong>, de forma r\u00e1pida y sin perder la competitividad.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el otro lado de la vereda, hay una gran cantidad de talento joven deseoso de ingresar al mundo IT, al que le cuesta encontrar qui\u00e9n lo gu\u00ede y lo forme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la intenci\u00f3n de matchear las necesidades de ambas partes, desde IT Patagonia llevamos adelante desde hace algunos a\u00f1os un programa de formaci\u00f3n y mentoring integral en COBOL, en el que expertos <strong>capacitan y acompa\u00f1an en el rol de mentores a los nuevos talentos<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Leonardo Zrycki es uno de esos mentores. En primera persona, describe su actividad como \u201c<strong>ardua, pero divertida<\/strong>\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs realmente emotivo participar de un proyecto que, no s\u00f3lo federaliza y democratiza el conocimiento de muchas camadas de j\u00f3venes profesionales brind\u00e1ndoles oportunidades laborales en tecnolog\u00eda, sino que tambi\u00e9n resuelve una de las demandas m\u00e1s frecuentes de nuestros clientes\u201d, cuenta el IBM Champion 2023 zSystem.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTengo la firme convicci\u00f3n de que el mentoring de equipos de j\u00f3venes profesionales es <a href=\"https:\/\/www.linkedin.com\/pulse\/mainframe-mentoring-una-experiencia-de-alcance-federal-zrycki\/?trackingId=DRROejNYSxK9UmE0SCFb9Q%3D%3D\" target=\"_blank\" rel=\"noreferrer noopener\">el mejor instrumento que tienen las empresas y organizaciones para refrescar su pir\u00e1mide de recursos humanos<\/a> y obtener resultados palpables en poco tiempo\u201d, sintetiza.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"IT Patagonia - Caso ICBC - Guillermo Tolosa\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/u-Vaooe830I?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\">Conoc\u00e9 el caso de \u00e9xito de ICBC-IT Patagonia.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusiones<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">COBOL es el lenguaje de programaci\u00f3n m\u00e1s utilizado en aplicaciones que requieren un alto rendimiento y bajo mantenimiento, por la confianza, solidez y seguridad que provee.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con 60 a\u00f1os de existencia, no ha surgido otro lenguaje que lo reemplace. Por eso, las grandes compa\u00f1\u00edas del mundo que sustentan sus sistemas core en mainframes, lo siguen utilizando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La transformaci\u00f3n digital y la aparici\u00f3n de nuevos lenguajes y entornos de programaci\u00f3n provocaron la escasez de perfiles senior y semi senior. Este contexto abre una gran oportunidad de desarrollo profesional en el campo de la programaci\u00f3n en COBOL.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a data-type=\"page\" data-id=\"5866\" href=\"https:\/\/itpatagonia.live\/es\/es_es\/servicios\/\">COBOL Studio de IT Patagonia<\/a> provee recursos expertos en an\u00e1lisis, dise\u00f1o, desarrollo, control de calidad e implementaci\u00f3n de soluciones inform\u00e1ticas en lenguaje COBOL, en diversas plataformas.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contactanos para <a href=\"https:\/\/itpatagonia.live\/index.php\/contacto\/\" data-type=\"page\" data-id=\"1370\">obtener m\u00e1s informaci\u00f3n<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Te contamos los aspectos que explican por qu\u00e9 el lenguaje insignia del sistema financiero est\u00e1 m\u00e1s vivo que nunca y sigue demandando nuevos talentos.<\/p>","protected":false},"author":3,"featured_media":9579,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[173],"tags":[32,38,37,36,33],"class_list":["post-9001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-modernizacion-core","tag-cobol","tag-desarrolladores-cobol","tag-digital-talent","tag-formacion","tag-mainframe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>COBOL: \u00bfpor qu\u00e9 sigue tan vigente como el primer d\u00eda?<\/title>\n<meta name=\"description\" content=\"Te contamos los aspectos que explican por qu\u00e9 Cobol, el lenguaje insignia del sistema financiero, sigue demandando nuevos talentos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/itpatagonia.live\/es\/blog\/cobol-por-que-sigue-vigente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COBOL, el lenguaje &quot;cancelado&quot; que sigue tan vigente como el primer d\u00eda\" \/>\n<meta property=\"og:description\" content=\"Te contamos los aspectos que explican por qu\u00e9 Cobol, el lenguaje insignia del sistema financiero, sigue demandando nuevos talentos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itpatagonia.live\/es\/blog\/cobol-por-que-sigue-vigente\/\" \/>\n<meta property=\"og:site_name\" content=\"IT Patagonia\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-19T19:47:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-20T13:27:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/12\/Cobol_Img-principal-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"870\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Valeria Frick\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valeria Frick\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/blog\\\/cobol-por-que-sigue-vigente#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/blog\\\/cobol-por-que-sigue-vigente\"},\"author\":{\"name\":\"Valeria Frick\",\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/#\\\/schema\\\/person\\\/ac8661c9cfc3e2a5a865f0fe97c9e1bb\"},\"headline\":\"COBOL, el lenguaje &#8220;cancelado&#8221; que sigue tan vigente como el primer d\u00eda\",\"datePublished\":\"2023-12-19T19:47:42+00:00\",\"dateModified\":\"2026-04-20T13:27:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/blog\\\/cobol-por-que-sigue-vigente\"},\"wordCount\":1845,\"publisher\":{\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/blog\\\/cobol-por-que-sigue-vigente#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/itpatagonia.live\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Cobol_Img-principal-2-1.jpg\",\"keywords\":[\"Cobol\",\"Desarrolladores Cobol\",\"Digital Talent\",\"Formaci\u00f3n\",\"Mainframe\"],\"articleSection\":[\"Modernizaci\u00f3n core\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/blog\\\/cobol-por-que-sigue-vigente\",\"url\":\"https:\\\/\\\/itpatagonia.live\\\/blog\\\/cobol-por-que-sigue-vigente\",\"name\":\"COBOL: \u00bfpor qu\u00e9 sigue tan vigente como el primer d\u00eda?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/blog\\\/cobol-por-que-sigue-vigente#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/blog\\\/cobol-por-que-sigue-vigente#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/itpatagonia.live\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Cobol_Img-principal-2-1.jpg\",\"datePublished\":\"2023-12-19T19:47:42+00:00\",\"dateModified\":\"2026-04-20T13:27:01+00:00\",\"description\":\"Te contamos los aspectos que explican por qu\u00e9 Cobol, el lenguaje insignia del sistema financiero, sigue demandando nuevos talentos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/blog\\\/cobol-por-que-sigue-vigente#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/itpatagonia.live\\\/blog\\\/cobol-por-que-sigue-vigente\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/blog\\\/cobol-por-que-sigue-vigente#primaryimage\",\"url\":\"https:\\\/\\\/itpatagonia.live\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Cobol_Img-principal-2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/itpatagonia.live\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Cobol_Img-principal-2-1.jpg\",\"width\":870,\"height\":330,\"caption\":\"Cobol, el lenguaje de programaci\u00f3n que sigue vigente.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/blog\\\/cobol-por-que-sigue-vigente#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/itpatagonia.live\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COBOL, el lenguaje \u00abcancelado\u00bb que sigue tan vigente como el primer d\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/#website\",\"url\":\"https:\\\/\\\/itpatagonia.live\\\/\",\"name\":\"IT Patagonia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/itpatagonia.live\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/#organization\",\"name\":\"IT Patagonia\",\"url\":\"https:\\\/\\\/itpatagonia.live\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/itpatagonia.live\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/IT-Patagonia-logo-web.png\",\"contentUrl\":\"https:\\\/\\\/itpatagonia.live\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/IT-Patagonia-logo-web.png\",\"width\":350,\"height\":100,\"caption\":\"IT Patagonia\"},\"image\":{\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/itpatagonia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/#\\\/schema\\\/person\\\/ac8661c9cfc3e2a5a865f0fe97c9e1bb\",\"name\":\"Valeria Frick\",\"url\":\"https:\\\/\\\/itpatagonia.live\\\/es\\\/blog\\\/author\\\/vfrick\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"COBOL: \u00bfpor qu\u00e9 sigue tan vigente como el primer d\u00eda?","description":"Te contamos los aspectos que explican por qu\u00e9 Cobol, el lenguaje insignia del sistema financiero, sigue demandando nuevos talentos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/itpatagonia.live\/es\/blog\/cobol-por-que-sigue-vigente\/","og_locale":"es_ES","og_type":"article","og_title":"COBOL, el lenguaje \"cancelado\" que sigue tan vigente como el primer d\u00eda","og_description":"Te contamos los aspectos que explican por qu\u00e9 Cobol, el lenguaje insignia del sistema financiero, sigue demandando nuevos talentos.","og_url":"https:\/\/itpatagonia.live\/es\/blog\/cobol-por-que-sigue-vigente\/","og_site_name":"IT Patagonia","article_published_time":"2023-12-19T19:47:42+00:00","article_modified_time":"2026-04-20T13:27:01+00:00","og_image":[{"width":870,"height":330,"url":"https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/12\/Cobol_Img-principal-2-1.jpg","type":"image\/jpeg"}],"author":"Valeria Frick","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Valeria Frick","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/itpatagonia.live\/blog\/cobol-por-que-sigue-vigente#article","isPartOf":{"@id":"https:\/\/itpatagonia.live\/blog\/cobol-por-que-sigue-vigente"},"author":{"name":"Valeria Frick","@id":"https:\/\/itpatagonia.live\/#\/schema\/person\/ac8661c9cfc3e2a5a865f0fe97c9e1bb"},"headline":"COBOL, el lenguaje &#8220;cancelado&#8221; que sigue tan vigente como el primer d\u00eda","datePublished":"2023-12-19T19:47:42+00:00","dateModified":"2026-04-20T13:27:01+00:00","mainEntityOfPage":{"@id":"https:\/\/itpatagonia.live\/blog\/cobol-por-que-sigue-vigente"},"wordCount":1845,"publisher":{"@id":"https:\/\/itpatagonia.live\/#organization"},"image":{"@id":"https:\/\/itpatagonia.live\/blog\/cobol-por-que-sigue-vigente#primaryimage"},"thumbnailUrl":"https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/12\/Cobol_Img-principal-2-1.jpg","keywords":["Cobol","Desarrolladores Cobol","Digital Talent","Formaci\u00f3n","Mainframe"],"articleSection":["Modernizaci\u00f3n core"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/itpatagonia.live\/blog\/cobol-por-que-sigue-vigente","url":"https:\/\/itpatagonia.live\/blog\/cobol-por-que-sigue-vigente","name":"COBOL: \u00bfpor qu\u00e9 sigue tan vigente como el primer d\u00eda?","isPartOf":{"@id":"https:\/\/itpatagonia.live\/#website"},"primaryImageOfPage":{"@id":"https:\/\/itpatagonia.live\/blog\/cobol-por-que-sigue-vigente#primaryimage"},"image":{"@id":"https:\/\/itpatagonia.live\/blog\/cobol-por-que-sigue-vigente#primaryimage"},"thumbnailUrl":"https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/12\/Cobol_Img-principal-2-1.jpg","datePublished":"2023-12-19T19:47:42+00:00","dateModified":"2026-04-20T13:27:01+00:00","description":"Te contamos los aspectos que explican por qu\u00e9 Cobol, el lenguaje insignia del sistema financiero, sigue demandando nuevos talentos.","breadcrumb":{"@id":"https:\/\/itpatagonia.live\/blog\/cobol-por-que-sigue-vigente#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/itpatagonia.live\/blog\/cobol-por-que-sigue-vigente"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/itpatagonia.live\/blog\/cobol-por-que-sigue-vigente#primaryimage","url":"https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/12\/Cobol_Img-principal-2-1.jpg","contentUrl":"https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/12\/Cobol_Img-principal-2-1.jpg","width":870,"height":330,"caption":"Cobol, el lenguaje de programaci\u00f3n que sigue vigente."},{"@type":"BreadcrumbList","@id":"https:\/\/itpatagonia.live\/blog\/cobol-por-que-sigue-vigente#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/itpatagonia.live\/"},{"@type":"ListItem","position":2,"name":"COBOL, el lenguaje \u00abcancelado\u00bb que sigue tan vigente como el primer d\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/itpatagonia.live\/#website","url":"https:\/\/itpatagonia.live\/","name":"IT Patagonia","description":"","publisher":{"@id":"https:\/\/itpatagonia.live\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itpatagonia.live\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/itpatagonia.live\/#organization","name":"IT Patagonia","url":"https:\/\/itpatagonia.live\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/itpatagonia.live\/#\/schema\/logo\/image\/","url":"https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/11\/IT-Patagonia-logo-web.png","contentUrl":"https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/11\/IT-Patagonia-logo-web.png","width":350,"height":100,"caption":"IT Patagonia"},"image":{"@id":"https:\/\/itpatagonia.live\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/itpatagonia\/"]},{"@type":"Person","@id":"https:\/\/itpatagonia.live\/#\/schema\/person\/ac8661c9cfc3e2a5a865f0fe97c9e1bb","name":"Valeria Frick","url":"https:\/\/itpatagonia.live\/es\/blog\/author\/vfrick"}]}},"_links":{"self":[{"href":"https:\/\/itpatagonia.live\/es\/wp-json\/wp\/v2\/posts\/9001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itpatagonia.live\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/itpatagonia.live\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/itpatagonia.live\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/itpatagonia.live\/es\/wp-json\/wp\/v2\/comments?post=9001"}],"version-history":[{"count":11,"href":"https:\/\/itpatagonia.live\/es\/wp-json\/wp\/v2\/posts\/9001\/revisions"}],"predecessor-version":[{"id":30360,"href":"https:\/\/itpatagonia.live\/es\/wp-json\/wp\/v2\/posts\/9001\/revisions\/30360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/itpatagonia.live\/es\/wp-json\/wp\/v2\/media\/9579"}],"wp:attachment":[{"href":"https:\/\/itpatagonia.live\/es\/wp-json\/wp\/v2\/media?parent=9001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/itpatagonia.live\/es\/wp-json\/wp\/v2\/categories?post=9001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/itpatagonia.live\/es\/wp-json\/wp\/v2\/tags?post=9001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}