{"id":134,"count":2,"description":"","link":"https:\/\/itpatagonia.live\/en\/blog\/tag\/modernizacion-mainframe","name":"Mainframe modernization","slug":"modernizacion-mainframe","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Modernizaci\u00f3n mainframe archivos - IT Patagonia<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modernizaci\u00f3n mainframe archivos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itpatagonia.live\/en\/es_es\/blog\/tag\/modernizacion-mainframe\/\" \/>\n<meta property=\"og:site_name\" content=\"IT Patagonia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/es_es\\\/blog\\\/tag\\\/modernizacion-mainframe\",\"url\":\"https:\\\/\\\/itpatagonia.live\\\/es_es\\\/blog\\\/tag\\\/modernizacion-mainframe\",\"name\":\"Modernizaci\u00f3n mainframe archivos - IT Patagonia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/es_es\\\/blog\\\/tag\\\/modernizacion-mainframe#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/es_es\\\/blog\\\/tag\\\/modernizacion-mainframe#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/itpatagonia.live\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modernizaci\u00f3n mainframe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/#website\",\"url\":\"https:\\\/\\\/itpatagonia.live\\\/\",\"name\":\"IT Patagonia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/itpatagonia.live\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/#organization\",\"name\":\"IT Patagonia\",\"url\":\"https:\\\/\\\/itpatagonia.live\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/itpatagonia.live\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/IT-Patagonia-logo-web.png\",\"contentUrl\":\"https:\\\/\\\/itpatagonia.live\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/IT-Patagonia-logo-web.png\",\"width\":350,\"height\":100,\"caption\":\"IT Patagonia\"},\"image\":{\"@id\":\"https:\\\/\\\/itpatagonia.live\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/itpatagonia\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Modernizaci\u00f3n mainframe archivos - IT Patagonia","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Modernizaci\u00f3n mainframe archivos","og_url":"https:\/\/itpatagonia.live\/en\/es_es\/blog\/tag\/modernizacion-mainframe\/","og_site_name":"IT Patagonia","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/itpatagonia.live\/es_es\/blog\/tag\/modernizacion-mainframe","url":"https:\/\/itpatagonia.live\/es_es\/blog\/tag\/modernizacion-mainframe","name":"Mainframe Modernization Archives - IT Patagonia","isPartOf":{"@id":"https:\/\/itpatagonia.live\/#website"},"breadcrumb":{"@id":"https:\/\/itpatagonia.live\/es_es\/blog\/tag\/modernizacion-mainframe#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/itpatagonia.live\/es_es\/blog\/tag\/modernizacion-mainframe#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/itpatagonia.live\/"},{"@type":"ListItem","position":2,"name":"Modernizaci\u00f3n mainframe"}]},{"@type":"WebSite","@id":"https:\/\/itpatagonia.live\/#website","url":"https:\/\/itpatagonia.live\/","name":"IT Patagonia","description":"","publisher":{"@id":"https:\/\/itpatagonia.live\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itpatagonia.live\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/itpatagonia.live\/#organization","name":"IT Patagonia","url":"https:\/\/itpatagonia.live\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/itpatagonia.live\/#\/schema\/logo\/image\/","url":"https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/11\/IT-Patagonia-logo-web.png","contentUrl":"https:\/\/itpatagonia.live\/wp-content\/uploads\/2023\/11\/IT-Patagonia-logo-web.png","width":350,"height":100,"caption":"IT Patagonia"},"image":{"@id":"https:\/\/itpatagonia.live\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/itpatagonia\/"]}]}},"_links":{"self":[{"href":"https:\/\/itpatagonia.live\/en\/wp-json\/wp\/v2\/tags\/134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itpatagonia.live\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/itpatagonia.live\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/itpatagonia.live\/en\/wp-json\/wp\/v2\/posts?tags=134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}